{"id":589,"count":2,"description":"","link":"https:\/\/feverishthoughts.com\/webdesign\/tag\/shout-out\/","name":"shout out","slug":"shout-out","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/feverishthoughts.com\/webdesign\/wp-json\/wp\/v2\/tags\/589","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/feverishthoughts.com\/webdesign\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/feverishthoughts.com\/webdesign\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/feverishthoughts.com\/webdesign\/wp-json\/wp\/v2\/posts?tags=589"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}